{"id":47216,"date":"2018-06-18T09:22:01","date_gmt":"2018-06-18T09:22:01","guid":{"rendered":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg"},"modified":"2018-06-18T09:22:01","modified_gmt":"2018-06-18T09:22:01","slug":"4-bed-dorm-ensuite_01-2","status":"inherit","type":"attachment","link":"https:\/\/www.santjordihostels.com\/es\/sant-jordi-hostel-rock-palace\/4-bed-dorm-ensuite_01-2\/","title":{"rendered":"4-Bed Dorm ensuite Rock Palace Hostel Barcelona"},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-47216","attachment","type-attachment","status-inherit","hentry","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Sant Jordi Hostels\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/santjordihostels\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@santjordihostel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\",\"url\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\",\"name\":\"4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels\",\"isPartOf\":{\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#website\"},\"datePublished\":\"2018-06-18T09:22:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.santjordihostels.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rock Palace\",\"item\":\"https:\/\/www.santjordihostels.com\/es\/sant-jordi-hostel-rock-palace\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4-Bed Dorm ensuite Rock Palace Hostel Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#website\",\"url\":\"https:\/\/www.santjordihostels.com\/pt-br\/\",\"name\":\"Sant Jordi Hostels\",\"description\":\"Award winning Barcelona Hostels. Modern Facilities. Great Locations. Fun Activities. The best Hostels Barcelona for good times and great accommodations.\",\"publisher\":{\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.santjordihostels.com\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#organization\",\"name\":\"Sant Jordi Hostels\",\"url\":\"https:\/\/www.santjordihostels.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/SJ_hd-logo2_2x.png\",\"contentUrl\":\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/SJ_hd-logo2_2x.png\",\"width\":163,\"height\":130,\"caption\":\"Sant Jordi Hostels\"},\"image\":{\"@id\":\"https:\/\/www.santjordihostels.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/santjordihostels\/\",\"https:\/\/x.com\/santjordihostel\",\"https:\/\/www.instagram.com\/santjordihostels\/\",\"https:\/\/www.pinterest.es\/santjordihostels\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","og_locale":"es_ES","og_type":"article","og_title":"4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels","og_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","og_site_name":"Sant Jordi Hostels","article_publisher":"https:\/\/www.facebook.com\/santjordihostels\/","og_image":[{"width":900,"height":600,"url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@santjordihostel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","name":"4-Bed Dorm ensuite Rock Palace Hostel Barcelona - Sant Jordi Hostels","isPartOf":{"@id":"https:\/\/www.santjordihostels.com\/pt-br\/#website"},"datePublished":"2018-06-18T09:22:01+00:00","breadcrumb":{"@id":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.santjordihostels.com\/es\/"},{"@type":"ListItem","position":2,"name":"Rock Palace","item":"https:\/\/www.santjordihostels.com\/es\/sant-jordi-hostel-rock-palace\/"},{"@type":"ListItem","position":3,"name":"4-Bed Dorm ensuite Rock Palace Hostel Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/www.santjordihostels.com\/pt-br\/#website","url":"https:\/\/www.santjordihostels.com\/pt-br\/","name":"Sant Jordi Hostels","description":"Award winning Barcelona Hostels. Modern Facilities. Great Locations. Fun Activities. The best Hostels Barcelona for good times and great accommodations.","publisher":{"@id":"https:\/\/www.santjordihostels.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.santjordihostels.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.santjordihostels.com\/pt-br\/#organization","name":"Sant Jordi Hostels","url":"https:\/\/www.santjordihostels.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.santjordihostels.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/SJ_hd-logo2_2x.png","contentUrl":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/SJ_hd-logo2_2x.png","width":163,"height":130,"caption":"Sant Jordi Hostels"},"image":{"@id":"https:\/\/www.santjordihostels.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/santjordihostels\/","https:\/\/x.com\/santjordihostel","https:\/\/www.instagram.com\/santjordihostels\/","https:\/\/www.pinterest.es\/santjordihostels"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-300x200.jpg 300w, https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-768x512.jpg 768w, https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":900,"height":600,"file":"4-Bed-Dorm-ensuite_01.jpg","sizes":{"thumbnail":{"file":"4-Bed-Dorm-ensuite_01-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-150x150.jpg"},"medium":{"file":"4-Bed-Dorm-ensuite_01-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-300x200.jpg"},"medium_large":{"file":"4-Bed-Dorm-ensuite_01-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01-768x512.jpg"},"full":{"file":"4-Bed-Dorm-ensuite_01.jpg","width":900,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33081,"source_url":"https:\/\/www.santjordihostels.com\/wp-content\/uploads\/4-Bed-Dorm-ensuite_01.jpg","_links":{"self":[{"href":"https:\/\/www.santjordihostels.com\/es\/wp-json\/wp\/v2\/media\/47216"}],"collection":[{"href":"https:\/\/www.santjordihostels.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.santjordihostels.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.santjordihostels.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santjordihostels.com\/es\/wp-json\/wp\/v2\/comments?post=47216"}]}}